{"id":438,"count":1,"description":"","link":"https:\/\/nero-luce.com\/it\/categoria-prodotto\/video\/","name":"Realizzazione Video pubblicitari","slug":"video","taxonomy":"product_cat","parent":0,"meta":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v20.2.1 - https:\/\/yoast.com\/wordpress\/plugins\/seo\/ -->\n<title>Realizzazione video pubblicitari per gelaterie e bar - Neroluce<\/title>\n<meta name=\"description\" content=\"Realizziamo video pubblicitari per gelaterie e bar, un nuovo modo nuovo di prendere per la gola i vostri clienti.\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/nero-luce.com\/it\/categoria-prodotto\/video\/\" \/>\n<meta property=\"og:locale\" content=\"fr_FR\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Realizzazione video pubblicitari per gelaterie e bar - Neroluce\" \/>\n<meta property=\"og:description\" content=\"Realizziamo video pubblicitari per gelaterie e bar, un nuovo modo nuovo di prendere per la gola i vostri clienti.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/nero-luce.com\/it\/categoria-prodotto\/video\/\" \/>\n<meta property=\"og:site_name\" content=\"Neroluce\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"CollectionPage\",\"@id\":\"https:\/\/nero-luce.com\/it\/categoria-prodotto\/video\/\",\"url\":\"https:\/\/nero-luce.com\/it\/categoria-prodotto\/video\/\",\"name\":\"Realizzazione video pubblicitari per gelaterie e bar - Neroluce\",\"isPartOf\":{\"@id\":\"https:\/\/nero-luce.com\/it\/#website\"},\"description\":\"Realizziamo video pubblicitari per gelaterie e bar, un nuovo modo nuovo di prendere per la gola i vostri clienti.\",\"breadcrumb\":{\"@id\":\"https:\/\/nero-luce.com\/it\/categoria-prodotto\/video\/#breadcrumb\"},\"inLanguage\":\"fr-FR\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/nero-luce.com\/it\/categoria-prodotto\/video\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\/\/nero-luce.com\/fr\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Realizzazione Video pubblicitari\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/nero-luce.com\/it\/#website\",\"url\":\"https:\/\/nero-luce.com\/it\/\",\"name\":\"Neroluce\",\"description\":\"Insegne e accessori per gelaterie\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/nero-luce.com\/it\/?s={search_term_string}\"},\"query-input\":\"required name=search_term_string\"}],\"inLanguage\":\"fr-FR\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Realizzazione video pubblicitari per gelaterie e bar - Neroluce","description":"Realizziamo video pubblicitari per gelaterie e bar, un nuovo modo nuovo di prendere per la gola i vostri clienti.","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/nero-luce.com\/it\/categoria-prodotto\/video\/","og_locale":"fr_FR","og_type":"article","og_title":"Realizzazione video pubblicitari per gelaterie e bar - Neroluce","og_description":"Realizziamo video pubblicitari per gelaterie e bar, un nuovo modo nuovo di prendere per la gola i vostri clienti.","og_url":"https:\/\/nero-luce.com\/it\/categoria-prodotto\/video\/","og_site_name":"Neroluce","twitter_card":"summary_large_image","schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"CollectionPage","@id":"https:\/\/nero-luce.com\/it\/categoria-prodotto\/video\/","url":"https:\/\/nero-luce.com\/it\/categoria-prodotto\/video\/","name":"Realizzazione video pubblicitari per gelaterie e bar - Neroluce","isPartOf":{"@id":"https:\/\/nero-luce.com\/it\/#website"},"description":"Realizziamo video pubblicitari per gelaterie e bar, un nuovo modo nuovo di prendere per la gola i vostri clienti.","breadcrumb":{"@id":"https:\/\/nero-luce.com\/it\/categoria-prodotto\/video\/#breadcrumb"},"inLanguage":"fr-FR"},{"@type":"BreadcrumbList","@id":"https:\/\/nero-luce.com\/it\/categoria-prodotto\/video\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/nero-luce.com\/fr\/"},{"@type":"ListItem","position":2,"name":"Realizzazione Video pubblicitari"}]},{"@type":"WebSite","@id":"https:\/\/nero-luce.com\/it\/#website","url":"https:\/\/nero-luce.com\/it\/","name":"Neroluce","description":"Insegne e accessori per gelaterie","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/nero-luce.com\/it\/?s={search_term_string}"},"query-input":"required name=search_term_string"}],"inLanguage":"fr-FR"}]}},"acf":[],"_links":{"self":[{"href":"https:\/\/nero-luce.com\/fr\/wp-json\/wp\/v2\/product_cat\/438"}],"collection":[{"href":"https:\/\/nero-luce.com\/fr\/wp-json\/wp\/v2\/product_cat"}],"about":[{"href":"https:\/\/nero-luce.com\/fr\/wp-json\/wp\/v2\/taxonomies\/product_cat"}],"wp:post_type":[{"href":"https:\/\/nero-luce.com\/fr\/wp-json\/wp\/v2\/product?product_cat=438"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}